{"id":1002,"date":"2023-03-09T11:32:33","date_gmt":"2023-03-09T10:32:33","guid":{"rendered":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/?p=1002"},"modified":"2023-11-06T11:28:30","modified_gmt":"2023-11-06T10:28:30","slug":"garten-fit-fuer-den-fruehling-machen","status":"publish","type":"post","link":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/","title":{"rendered":"Garten fit f\u00fcr den Fr\u00fchling machen"},"content":{"rendered":"\n<p>Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling.<\/p>\n\n\n\n<p>Wer seinen <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten\/\">Garten<\/a> liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen Temperaturen des neuen Jahres erwacht die Natur aus ihrem Winterschlaf.<\/p>\n\n\n\n<p>Gehen Sie eine Runde durch Ihren Garten und machen Sie eine Bestandsaufnahme. Welche Pflanzen haben den <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/news-infos\/13-wichtige-gartenarbeiten-im-herbst\/\">Herbst<\/a> und <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/diese-fehler-schaden-ihrem-garten-im-winter\/\">Winter<\/a> \u00fcberlebt? Schauen Sie genau hin: Nicht alle Pflanzen sind eingegangen, nur weil es auf den ersten Blick so aussieht. Viele Pflanzen haben sich nur zur\u00fcckgezogen und zeigen ihre Pracht erst, wenn ihre Zeit gekommen ist.<\/p>\n\n\n\n<p>Der Fr\u00fchling naht und die ersten kleinen Fr\u00fchbl\u00fcher z.&nbsp;B. Krokusse, Schneegl\u00f6ckchen und viele mehr, die ihre Sch\u00f6nheit zeigen wollen, sobald der Frost sich verabschiedet hat, damit aus Ihrem Garten im Fr\u00fchling ein kleines Paradies wird und die ersten warmen Tagen des Jahres anstehen, brauchen die Pflanzen besondere Pflege.<\/p>\n\n\n\n<p>Die Pflanzen, Str\u00e4ucher, B\u00e4ume m\u00fcssen geschnitten, trockne \u00c4ste und Geh\u00f6lze entfernen, der Boden muss aufger\u00fcttelt, um gestochen und ged\u00fcngt werden, damit es die Pflanzen zum Treiben und Bl\u00fchen anregt. <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/12-tipps-rund-ums-rasenmaehen\/\">Rasen sollte geschnitten und kultiviert werden<\/a>, damit das Moos keine Chance hat sich weiterzuverbreiten, die Beete f\u00fcr Gem\u00fcse und Blumen neu angelegen.<\/p>\n\n\n\n<p>Frost empfindliche Pflanzen k\u00f6nnen durch sp\u00e4te Bodenfr\u00f6ste empfindlich gesch\u00e4digt werden. Daher kommt es im Fr\u00fchjahr auch auf den richtigen Frostschutz an. Den Frostschutz besorgt normalerweise die Natur selbst mit einer winterlichen Decke aus Schnee was in unserer Region sehr selten ist, deshalb k\u00f6nnen n\u00e4chtlichen Fr\u00f6ste f\u00fcr einigen Pflanzen zum Verh\u00e4ngnis werden, vor allem solche, die in K\u00fcbeln stehen, aber auch bl\u00fchende <a href=\"https:\/\/www.gruenlandstaudenhof.de\/Shop\/obstpflanzen\">Obstb\u00e4ume<\/a>, <a href=\"https:\/\/www.gruenlandstaudenhof.de\/Shop\/\">Rosen<\/a> und viele andere frostempfindliche Pflanzen, daf\u00fcr gibt es den k\u00fcnstlichen Frostschutz aus verschiedenen Materialien, die ihre Pflanzen sicher sch\u00fctzen, dabei ansehnlich sind mehrfach verwendbar sind und die zum Teil auch verrotten.<\/p>\n\n\n\n<p>Nat\u00fcrlich muss man auch den Terrassenboden und die Gartenwege reinigen. Boden um die Rosen im Fr\u00fchjahr mehrmals auflockern. K\u00fcbelpflanzen in passende T\u00f6pfe umtopfen. Die Blumenk\u00e4sten von alter Erde befreien und die eingegangenen Pflanzen vernichten. Balkon- und Terrassenm\u00f6bel reinigen und mit dem entsprechenden Pflegemittel richtig behandeln, damit alles wieder wie neu und frisch aussieht. Jetzt kann der Fr\u00fchling kommen, wenn die Arbeit getan ist.<\/p>\n\n\n\n<p><strong>Schreibt eure Meinung zu Thema<\/strong><\/p>\n\n\n\n<p>Wie macht Ihr Euren Garten fit f\u00fcr den Fr\u00fchling?<\/p><div id=\"gruen-1582675593\" class=\"gruen-test gruen-entity-placement\"><div class=\"gruen-adlabel\">Werbung<\/div><div class=\"InPageAdContainer\">\r\n\r\n<!--\t<span class=\"InPageAdHeaderTextWERBUNG\">WERBUNG<\/span>-->\r\n\r\n\t<div style=\"display: flex; flex-direction: column; align-items: center; gap: 10px;\">\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t <div id=\"gruen-4166355682\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-1018748266\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=4faac1d62285ab69760be3d76263a584\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/66d9fda5291b6d78b60c5d8e10978efe.gif\"\r\n                 alt=\"PAJ-GPS\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"468\"                height=\"60\"                 loading=\"lazy\">\r\n        <\/a>\r\n        <\/div><\/div>\r\n\t\t<\/div>\r\n\t\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t<div id=\"gruen-1106600776\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-1549720868\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=4954f11053654d57933f23e5cb3b8edb\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/f714499735a541f9a50e6ede47f1471f.gif\"\r\n                 alt=\"D\u00fcnger-Shop.de\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"468\"                height=\"60\"                 loading=\"lazy\">\r\n        <\/a>\r\n        <\/div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t\r\n\t<div>\r\n\t<script data-cmp-vendor=\"755\" type=\"text\/plain\" async class=\"cmplazyload\" data-cmp-src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4674519130717366\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n\t<ins type=\"text\/plain\" class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4674519130717366\"\r\n     data-ad-slot=\"3839778248\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n\t<script type=\"text\/plain\" data-cmp-vendor=\"755\" class=\"cmplazyload\">\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n\t<\/script>\r\n     <\/div>\r\n\r\n\t\r\n\t\r\n\r\n<\/div>\r\n\r\n<\/div>\n<div id=\"gruen-2089373929\" class=\"gruen-footer_468x60_bottom gruen-entity-placement\"><div class=\"gruen-adlabel\">Werbung<\/div><div class=\"InPageAdContainer\">\r\n\r\n<!--\t<span class=\"InPageAdHeaderTextWERBUNG\">WERBUNG<\/span>-->\r\n\r\n\t<div style=\"display: flex; flex-direction: column; align-items: center; gap: 10px;\">\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t <div id=\"gruen-4166355682\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-2197500676\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=d0ce7d77ad01e9bed66b566d8edfb927\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/40530b9600e52758b460dd9fca468936.gif\"\r\n                 alt=\"agrarflora\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"970\"                height=\"250\"                 loading=\"lazy\">\r\n        <\/a>\r\n        \r\n\r\n\r\n\r\n<\/div><\/div>\r\n\t\t<\/div>\r\n\t\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t<div id=\"gruen-1106600776\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-48193348\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=3376cc839c9ed553843a69820bcef078\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/5f2f6490ce1c8fc585d5e160b95a79df.gif\"\r\n                 alt=\"Puzzle.de\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"468\"                height=\"60\"                 loading=\"lazy\">\r\n        <\/a>\r\n        <\/div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t\r\n\t<div>\r\n\t<script data-cmp-vendor=\"755\" type=\"text\/plain\" async class=\"cmplazyload\" data-cmp-src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4674519130717366\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n\t<ins type=\"text\/plain\" class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4674519130717366\"\r\n     data-ad-slot=\"3839778248\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n\t<script type=\"text\/plain\" data-cmp-vendor=\"755\" class=\"cmplazyload\">\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n\t<\/script>\r\n     <\/div>\r\n\r\n\t\r\n\t\r\n\r\n<\/div>\r\n\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen Temperaturen des neuen Jahres erwacht die Natur aus ihrem Winterschlaf. Gehen Sie eine Runde durch Ihren Garten und machen Sie eine Bestandsaufnahme. Welche Pflanzen haben den Herbst und Winter \u00fcberlebt? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3174,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[645,644,643,10,21,32,149,75],"tags":[482,11,127],"class_list":["post-1002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fruehling","category-gartenkalender","category-gaertnerei","category-haus-garten","category-pflanzen","category-tipps","category-ratgeber","category-tiere","tag-fruehling","tag-garten","tag-ratgeber","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Garten fit f\u00fcr den Fr\u00fchling machen - Gr\u00fcnlandstaudenhof<\/title>\n<meta name=\"description\" content=\"Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Garten fit f\u00fcr den Fr\u00fchling machen - Gr\u00fcnlandstaudenhof\" \/>\n<meta property=\"og:description\" content=\"Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/\" \/>\n<meta property=\"og:site_name\" content=\"Gr\u00fcnlandstaudenhof\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gruenlandstaudenhof\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-09T10:32:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T10:28:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi-1016x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1016\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GSH_Oberhausen\" \/>\n<meta name=\"twitter:site\" content=\"@GSH_Oberhausen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Garten fit f\u00fcr den Fr\u00fchling machen - Gr\u00fcnlandstaudenhof","description":"Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/","og_locale":"de_DE","og_type":"article","og_title":"Garten fit f\u00fcr den Fr\u00fchling machen - Gr\u00fcnlandstaudenhof","og_description":"Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen","og_url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/","og_site_name":"Gr\u00fcnlandstaudenhof","article_publisher":"https:\/\/www.facebook.com\/gruenlandstaudenhof","article_published_time":"2023-03-09T10:32:33+00:00","article_modified_time":"2023-11-06T10:28:30+00:00","og_image":[{"width":1016,"height":1024,"url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi-1016x1024.png","type":"image\/png"}],"author":"Administrator","twitter_card":"summary_large_image","twitter_creator":"@GSH_Oberhausen","twitter_site":"@GSH_Oberhausen","twitter_misc":{"Verfasst von":"Administrator","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#article","isPartOf":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/"},"author":{"name":"Administrator","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/person\/5ddb7b7caf3cb3446b4b3c35e2724a03"},"headline":"Garten fit f\u00fcr den Fr\u00fchling machen","datePublished":"2023-03-09T10:32:33+00:00","dateModified":"2023-11-06T10:28:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/"},"wordCount":411,"commentCount":1,"publisher":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#organization"},"image":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png","keywords":["Fr\u00fchling","Garten","Ratgeber"],"articleSection":["Fr\u00fchling","Gartenkalender","G\u00e4rtnerei","Haus &amp; Garten","Pflanzen","R-Tipps","Ratgeber","Tiere"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/","name":"Garten fit f\u00fcr den Fr\u00fchling machen - Gr\u00fcnlandstaudenhof","isPartOf":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#primaryimage"},"image":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png","datePublished":"2023-03-09T10:32:33+00:00","dateModified":"2023-11-06T10:28:30+00:00","description":"Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen","breadcrumb":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#primaryimage","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png","contentUrl":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png","width":1183,"height":1192,"caption":"Fr\u00fchling"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/garten-fit-fuer-den-fruehling-machen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/"},{"@type":"ListItem","position":2,"name":"Garten fit f\u00fcr den Fr\u00fchling machen"}]},{"@type":"WebSite","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#website","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/","name":"Gr\u00fcnlandstaudenhof","description":"Landwirtschaft, Gartenbau, Landhandel","publisher":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#organization","name":"Gr\u00fcnlandstaudenhof","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/logo\/image\/","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2016\/03\/logo_briefkopf_OT.png","contentUrl":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2016\/03\/logo_briefkopf_OT.png","width":504,"height":504,"caption":"Gr\u00fcnlandstaudenhof"},"image":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gruenlandstaudenhof","https:\/\/x.com\/GSH_Oberhausen","https:\/\/www.instagram.com\/gruenlandstaudenhof\/"]},{"@type":"Person","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/person\/5ddb7b7caf3cb3446b4b3c35e2724a03","name":"Administrator"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png",1183,1192,false],"thumbnail":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi-150x150.png",150,150,true],"medium":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi-298x300.png",298,300,true],"medium_large":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi-768x774.png",768,774,true],"large":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi-1016x1024.png",1016,1024,true],"1536x1536":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png",1183,1192,false],"2048x2048":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png",1183,1192,false],"ocean-thumb-m":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png",595,600,false],"ocean-thumb-ml":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png",447,450,false],"ocean-thumb-l":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2021\/09\/Tumbnail-Fru\u0308hling-Fledi.png",695,700,false]},"uagb_author_info":{"display_name":"Administrator","author_link":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/author\/administrator\/"},"uagb_comment_info":1,"uagb_excerpt":"Wenn der Winter zu Ende geht, beginnt der Fr\u00fchling. Wer seinen Garten liebt, wartet jetzt auf die Zeit, dass es losgeht. Mit den ersten warmen Temperaturen des neuen Jahres erwacht die Natur aus ihrem Winterschlaf. Gehen Sie eine Runde durch Ihren Garten und machen Sie eine Bestandsaufnahme. Welche Pflanzen haben den Herbst und Winter \u00fcberlebt?&hellip;","_links":{"self":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/posts\/1002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/comments?post=1002"}],"version-history":[{"count":0,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/posts\/1002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/media\/3174"}],"wp:attachment":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/media?parent=1002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/categories?post=1002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/tags?post=1002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}