{"id":1300,"date":"2018-02-23T14:20:31","date_gmt":"2018-02-23T13:20:31","guid":{"rendered":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/?p=1300"},"modified":"2020-10-21T12:43:35","modified_gmt":"2020-10-21T10:43:35","slug":"gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese","status":"publish","type":"post","link":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/gruenlandstaudenhof\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/","title":{"rendered":"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse"},"content":{"rendered":"<p>Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an.<\/p>\n<p>In Absprache mit Ihnen beliefern wir Ihren Kindergarten oder Ihre Schule t\u00e4glich mit frischem <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/unser-frisches-obst-und-gemuese\/\">Obst und Gem\u00fcse<\/a>. Unter Umst\u00e4nden k\u00f6nnen Sie sich die Lieferung mit Obst und Gem\u00fcse durch die EU, Bund, L\u00e4nder oder die Kommune f\u00f6rdern lassen.<\/p>\n<h2>Naturbelassener Anbau<\/h2>\n<p>Bei unserem Obst und Gem\u00fcse achten wir selbstverst\u00e4ndlich nicht nur auf gute Qualit\u00e4t sondern auch auf <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/news-infos\/individuelle-landwirtschaft\/\">Naturbelassenheit<\/a> d.h. ohne k\u00fcnstliche Zusatzstoffe, Pestiziden\/Bioziden und nachhaltigem Anbau.<\/p>\n<p>Nachhaltig bedeutet, dass die Landfl\u00e4che zum Anbau schonend genutzt wird. Die biologische Diversit\u00e4t (Vielfalt), die Vitalit\u00e4t und Produktivit\u00e4t des Bodens (z.B. Boden wird nicht ausgelaugt oder \u00fcberd\u00fcngt), die Pflanzen- und Tierwelt bleibt dabei erhalten.<\/p>\n<p>Wir setzen bei nachhaltigen Anbau ohne Exzesse in der Natur. Die Fruchtbarkeit des Bodens wird bei uns durch organische <a href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/haus-garten\/top-15-duenger-selber-machen\/\">D\u00fcnger<\/a>, Kompost, Gr\u00fcnd\u00fcngung und eine vielseitige Fruchtfolge gef\u00f6rdert. Bei der Sch\u00e4dlingsbek\u00e4mpfung setzen wir ausschlie\u00dflich \u00f6kologische nat\u00fcrliche Verfahren ein, dazu z\u00e4hlt Brennesseljauche.<\/p>\n<p>Der Anbau der Fr\u00fcchte des Feldes geht dabei im Einklang mit der Natur einher, statt nach dem vorherrschenden industriell-konventionellen Anbau.<\/p>\n<h2>Was ist der industriell-konventionellen Anbau?<\/h2>\n<p>Der industriell-konventionellen Anbau ist sch\u00e4dlich f\u00fcr Boden, Pflanzen und Tiere. Er ist verantwortlich f\u00fcr Bodenerosionen, Wasserverschmutzung (insbesondere Grundwasser\/Trinkwasser) und Zerst\u00f6rt die nat\u00fcrlichen Lebensr\u00e4ume von Pflanzen, Tieren und Insekten.<\/p>\n<p>Die exzessive industrielle und konventionelle Landwirtschaft hat einen immens hohen Wasserverbrauch. Der Einsatz von chemischen D\u00fcngern und Pflanzenschutzmittel vergiftet den Boden und das Grundwasser. Das Pfl\u00fcgen der Erde in Verbindung mit den Giften zerst\u00f6rt den Lebensraum der Erdbewohner. Der Anbau von Monokulturen laugt und belastet den Boden.<\/p>\n<h2>Kurse und Seminare<\/h2>\n<p>Kommen Sie auch gerne auf uns zu, wenn Sie f\u00fcr Ihre Einrichtung an unseren Seminare in Sachen Nachhaltigkeit f\u00fcr Sch\u00fcler, Lehrer oder auch Eltern interessiert sind.<\/p><div id=\"gruen-2118545219\" class=\"gruen-test gruen-entity-placement\"><div class=\"gruen-adlabel\">Werbung<\/div><div class=\"InPageAdContainer\">\r\n\r\n<!--\t<span class=\"InPageAdHeaderTextWERBUNG\">WERBUNG<\/span>-->\r\n\r\n\t<div style=\"display: flex; flex-direction: column; align-items: center; gap: 10px;\">\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t <div id=\"gruen-623843301\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-3803548560\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=afe5c597b9b85393685b392bc7a2197f\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/de6ba0ec8bf267781909aebc02869847.gif\"\r\n                 alt=\"isolier-fuchs.de\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"728\"                height=\"90\"                 loading=\"lazy\">\r\n        <\/a>\r\n        <\/div><\/div>\r\n\t\t<\/div>\r\n\t\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t<div id=\"gruen-2770492343\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-31849505\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=3376cc839c9ed553843a69820bcef078\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/5f2f6490ce1c8fc585d5e160b95a79df.gif\"\r\n                 alt=\"Puzzle.de\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"468\"                height=\"60\"                 loading=\"lazy\">\r\n        <\/a>\r\n        <\/div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t\r\n\t<div>\r\n\t<script data-cmp-vendor=\"755\" type=\"text\/plain\" async class=\"cmplazyload\" data-cmp-src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4674519130717366\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n\t<ins type=\"text\/plain\" class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4674519130717366\"\r\n     data-ad-slot=\"3839778248\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n\t<script type=\"text\/plain\" data-cmp-vendor=\"755\" class=\"cmplazyload\">\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n\t<\/script>\r\n     <\/div>\r\n\r\n\t\r\n\t\r\n\r\n<\/div>\r\n\r\n<\/div>\n<div id=\"gruen-4067827406\" class=\"gruen-footer_468x60_bottom gruen-entity-placement\"><div class=\"gruen-adlabel\">Werbung<\/div><div class=\"InPageAdContainer\">\r\n\r\n<!--\t<span class=\"InPageAdHeaderTextWERBUNG\">WERBUNG<\/span>-->\r\n\r\n\t<div style=\"display: flex; flex-direction: column; align-items: center; gap: 10px;\">\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t <div id=\"gruen-623843301\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-842207507\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=3cc1ae0a8a851e58ee53d6b4f3692ead\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/54355b6352870b7cb8b0e213c42c630a.gif\"\r\n                 alt=\"Pepperworld Hot Shop\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"728\"                height=\"90\"                 loading=\"lazy\">\r\n        <\/a>\r\n        \r\n<\/div><\/div>\r\n\t\t<\/div>\r\n\t\r\n\t\t<div style=\"display: inline-block; padding-top:5px;\">\r\n\t\t\t<div id=\"gruen-2770492343\"><div class=\"gruen-adlabel\">Werbung<\/div><div id=\"gruen-3703677620\">        <a href=\"https:\/\/t.adcell.com\/p\/click?encodingId=d0ce7d77ad01e9bed66b566d8edfb927\" target=\"_blank\" rel=\"nofollow sponsored noopener\">\r\n            <img src=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/my-ads-cache\/40530b9600e52758b460dd9fca468936.gif\"\r\n                 alt=\"agrarflora\"\r\n                 style=\"max-width:100%;height:auto;\"\r\n                width=\"970\"                height=\"250\"                 loading=\"lazy\">\r\n        <\/a>\r\n        \r\n\r\n\r\n\r\n<\/div><\/div>\r\n\t\t<\/div>\r\n\t<\/div>\r\n\t\t\r\n\t<div>\r\n\t<script data-cmp-vendor=\"755\" type=\"text\/plain\" async class=\"cmplazyload\" data-cmp-src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-4674519130717366\"\r\n     crossorigin=\"anonymous\"><\/script>\r\n\t<ins type=\"text\/plain\" class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4674519130717366\"\r\n     data-ad-slot=\"3839778248\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n\t<script type=\"text\/plain\" data-cmp-vendor=\"755\" class=\"cmplazyload\">\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n\t<\/script>\r\n     <\/div>\r\n\r\n\t\r\n\t\r\n\r\n<\/div>\r\n\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir Ihren Kindergarten oder Ihre Schule t\u00e4glich mit frischem Obst und Gem\u00fcse. Unter Umst\u00e4nden k\u00f6nnen Sie sich die Lieferung mit Obst und Gem\u00fcse durch die EU, Bund, L\u00e4nder oder die Kommune f\u00f6rdern lassen. Naturbelassener Anbau [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","ocean_front_end_style_editor":"no","ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[60,98,13,94],"tags":[115,116,113,114],"class_list":["post-1300","post","type-post","status-publish","format-standard","hentry","category-gruenlandstaudenhof","category-landwirtschaft","category-buero","category-produkte","tag-kindergarten","tag-kita","tag-projekt-nachhaltigkeit","tag-schule","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse - Gr\u00fcnlandstaudenhof<\/title>\n<meta name=\"description\" content=\"Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse - Gr\u00fcnlandstaudenhof\" \/>\n<meta property=\"og:description\" content=\"Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/\" \/>\n<meta property=\"og:site_name\" content=\"Gr\u00fcnlandstaudenhof\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gruenlandstaudenhof\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-23T13:20:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T10:43:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2019\/01\/Logo192.png\" \/>\n\t<meta property=\"og:image:width\" content=\"192\" \/>\n\t<meta property=\"og:image:height\" content=\"192\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Administrator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GSH_Oberhausen\" \/>\n<meta name=\"twitter:site\" content=\"@GSH_Oberhausen\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse - Gr\u00fcnlandstaudenhof","description":"Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/","og_locale":"de_DE","og_type":"article","og_title":"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse - Gr\u00fcnlandstaudenhof","og_description":"Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir","og_url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/","og_site_name":"Gr\u00fcnlandstaudenhof","article_publisher":"https:\/\/www.facebook.com\/gruenlandstaudenhof","article_published_time":"2018-02-23T13:20:31+00:00","article_modified_time":"2020-10-21T10:43:35+00:00","og_image":[{"width":192,"height":192,"url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2019\/01\/Logo192.png","type":"image\/png"}],"author":"Administrator","twitter_card":"summary_large_image","twitter_creator":"@GSH_Oberhausen","twitter_site":"@GSH_Oberhausen","twitter_misc":{"Verfasst von":"Administrator","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/#article","isPartOf":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/"},"author":{"name":"Administrator","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/person\/5ddb7b7caf3cb3446b4b3c35e2724a03"},"headline":"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse","datePublished":"2018-02-23T13:20:31+00:00","dateModified":"2020-10-21T10:43:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/"},"wordCount":338,"commentCount":7,"publisher":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#organization"},"keywords":["Kindergarten","KITA","Projekt-Nachhaltigkeit","Schule"],"articleSection":["Gr\u00fcnlandstaudenhof","Landwirtschaft","Office","Produkte"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/","name":"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse - Gr\u00fcnlandstaudenhof","isPartOf":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#website"},"datePublished":"2018-02-23T13:20:31+00:00","dateModified":"2020-10-21T10:43:35+00:00","description":"Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir","breadcrumb":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/ratgeber\/buero\/gesundes-fuer-kindergraten-und-schule-unser-obst-und-gemuese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/"},{"@type":"ListItem","position":2,"name":"Gesundes f\u00fcr Kindergraten und Schule: Unser Obst und Gem\u00fcse"}]},{"@type":"WebSite","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#website","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/","name":"Gr\u00fcnlandstaudenhof","description":"Landwirtschaft, Gartenbau, Landhandel","publisher":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#organization","name":"Gr\u00fcnlandstaudenhof","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/logo\/image\/","url":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2016\/03\/logo_briefkopf_OT.png","contentUrl":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-content\/uploads\/2016\/03\/logo_briefkopf_OT.png","width":504,"height":504,"caption":"Gr\u00fcnlandstaudenhof"},"image":{"@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gruenlandstaudenhof","https:\/\/x.com\/GSH_Oberhausen","https:\/\/www.instagram.com\/gruenlandstaudenhof\/"]},{"@type":"Person","@id":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/#\/schema\/person\/5ddb7b7caf3cb3446b4b3c35e2724a03","name":"Administrator"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"ocean-thumb-m":false,"ocean-thumb-ml":false,"ocean-thumb-l":false},"uagb_author_info":{"display_name":"Administrator","author_link":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/author\/administrator\/"},"uagb_comment_info":7,"uagb_excerpt":"Im Zuge unserer Projektinitiative zur \u201eNachhaltigkeit\u201c bieten wir spezielle Angebote f\u00fcr Kinderg\u00e4rten und Schulen an. In Absprache mit Ihnen beliefern wir Ihren Kindergarten oder Ihre Schule t\u00e4glich mit frischem Obst und Gem\u00fcse. Unter Umst\u00e4nden k\u00f6nnen Sie sich die Lieferung mit Obst und Gem\u00fcse durch die EU, Bund, L\u00e4nder oder die Kommune f\u00f6rdern lassen. Naturbelassener Anbau&hellip;","_links":{"self":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/posts\/1300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/comments?post=1300"}],"version-history":[{"count":0,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/posts\/1300\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/media?parent=1300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/categories?post=1300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruenlandstaudenhof.de\/cms2\/wp-json\/wp\/v2\/tags?post=1300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}